{"id":3295,"date":"2025-06-25T08:19:45","date_gmt":"2025-06-25T08:19:45","guid":{"rendered":"http:\/\/72e718a9-aa3e-47f1-99b0-a540271f695c"},"modified":"2025-06-25T08:19:45","modified_gmt":"2025-06-25T08:19:45","slug":"escalacao-do-flamengo-2009","status":"publish","type":"post","link":"https:\/\/tsports.app.br\/perguntas-frequentes\/escalacao-do-flamengo-2009\/","title":{"rendered":"Escala\u00e7\u00e3o do flamengo 2009"},"content":{"rendered":"Goleiro Bruno; L\u00e9o Moura, \u00c1lvaro, Ronaldo Angelim, Juan (\u00c9verton); Maldonado (Tor\u00f3), Airton, Willians, Petkovi\u0107; Z\u00e9 Roberto (Emerson) e Adriano. t\u00e9cnico: Andrade. Diego, Everton Silva, Welinton, David, Lenon, Kl\u00e9berson, Fierro, D\u00eanis Marques, Bruno Mezenga.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('ognemalF_od_satageR_ed_ebulC_od_se5B%3C%epmac_semit_ed_atsiL\/ikiw\/gro.aidepikiw.tp\/\/:sptth'), '_blank')\">Veja a resposta completa em pt.wikipedia.org<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual era o time do Flamengo em 2010?<\/h2>\n\n<p>Nome | POS<\/p><table border=\"1\"><tr><td>Marcelo Lomba<\/td><td>G<\/td><\/tr><tr><td>Vin\u00edcius<\/td><td>G<\/td><\/tr><tr><td>Paulo Victor<\/td><td>G<\/td><\/tr><tr><td>Marcelo Carn\u00e9<\/td><td>G<\/td><\/tr><\/table><br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmth.serodatrebil-an-snaihtniroc-artnocneer-ognemalf-sona-ezod-sopa-edadilaer-avon-me\/ognemalf\/rb.moc.ecnal.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.lance.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual foi o time do Flamengo em 2010?<\/h2>\n\n\n<p><\/p><p>Nome | POS<\/p><table border=\"1\"><tr><td>Marcelo Lomba<\/td><td>G<\/td><\/tr><tr><td>Vin\u00edcius<\/td><td>G<\/td><\/tr><tr><td>Paulo Victor<\/td><td>G<\/td><\/tr><tr><td>Marcelo Carn\u00e9<\/td><td>G<\/td><\/tr><\/table><br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmth.serodatrebil-an-snaihtniroc-artnocneer-ognemalf-sona-ezod-sopa-edadilaer-avon-me\/ognemalf\/rb.moc.ecnal.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.lance.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual era o time do Flamengo na Copa Kirin de 1988?<\/h2>\n\n\n<p><\/p>Em P\u00e9: Cantarele, Leandro, Valmir, Delacir e Edinho e Paulo Cesar. Agachados: Gilmar Popoca, G\u00e9rson, M\u00e1rcio, Zico e Paloma.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmth.serodatrebil-an-snaihtniroc-artnocneer-ognemalf-sona-ezod-sopa-edadilaer-avon-me\/ognemalf\/rb.moc.ecnal.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.lance.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem era o camisa 9 do Flamengo em 2010?<\/h2>\n\n\n<p><\/p>Deivid chegou ao Flamengo no segundo semestre de 2010 com a expectativa de elevar o patamar do ataque Rubro-Negro que, naquela altura, com a sa\u00edda de V\u00e1gner Love, contava com Val Baiano como titular. O atacante s\u00f3 passou a usar a camisa 9 em 2011, ano em que formou um trio goleador com Ronaldinho Ga\u00facho e Thiago Neves.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmth.serodatrebil-an-snaihtniroc-artnocneer-ognemalf-sona-ezod-sopa-edadilaer-avon-me\/ognemalf\/rb.moc.ecnal.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.lance.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual era o elenco do Flamengo de 2009?<\/h2>\n\n\n<p><\/p>Em 2009, o Flamengo, que terminou campe\u00e3o brasileiro com o t\u00e9cnico Andrade, tinha como base: Bruno; L\u00e9o Moura, Ronaldo Angelim, David Braz e Juan; Airton, Willians e Tor\u00f3; Z\u00e9 Roberto e Adriano.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmth.serodatrebil-an-snaihtniroc-artnocneer-ognemalf-sona-ezod-sopa-edadilaer-avon-me\/ognemalf\/rb.moc.ecnal.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.lance.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual era o time do Flamengo em 2011?<\/h2>\n\n\n<p><\/p><p>Nome | POS<\/p><table border=\"1\"><tr><td>Deivid<\/td><td>A<\/td><\/tr><tr><td>Diego Maur\u00edcio<\/td><td>A<\/td><\/tr><tr><td>Luis Felipe<\/td><td>A<\/td><\/tr><tr><td>Negueba<\/td><td>A<\/td><\/tr><\/table><br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmth.serodatrebil-an-snaihtniroc-artnocneer-ognemalf-sona-ezod-sopa-edadilaer-avon-me\/ognemalf\/rb.moc.ecnal.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.lance.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual foi o elenco do Flamengo de 2019?<\/h2>\n\n\n<p><\/p><p>Nome | POS<\/p><table border=\"1\"><tr><td>Gerson8<\/td><td>M<\/td><\/tr><tr><td>Diego10<\/td><td>M<\/td><\/tr><tr><td>Giorgian de Arrascaeta14<\/td><td>M<\/td><\/tr><tr><td>Vinicius Souza15<\/td><td>M<\/td><\/tr><\/table><br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmth.serodatrebil-an-snaihtniroc-artnocneer-ognemalf-sona-ezod-sopa-edadilaer-avon-me\/ognemalf\/rb.moc.ecnal.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.lance.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem foi o campe\u00e3o brasileiro de 2009?<\/h2>\n\n\n<p>Flamengo<\/p>A S\u00e9rie A do Campeonato Brasileiro de Futebol de 2009 foi a 54. \u00aa edi\u00e7\u00e3o da principal divis\u00e3o do futebol brasileiro, vencida pelo Clube de Regatas do Flamengo.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('orielisarb-otanoepmac-od-oaceles-a-uocif-omoc-9002-atarp-ed-alob\/68243541\/di\/_\/ogitra\/atarp-ed-alob\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem foi o campe\u00e3o do Campeonato Brasileiro de 2009?<\/h2>\n\n\n<p><\/p>A edi\u00e7\u00e3o de 2009 foi vencida pelo Flamengo . O primeiro gol do torneio foi marcado por Igor aos 13 minutos da partida entre seu time, Sport e Barueri , que terminou empatada em 1 a 1. O atual campe\u00e3o S\u00e3o Paulo come\u00e7ou mal, perdendo para o Fluminense por 1 a 0.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('orielisarb-otanoepmac-od-oaceles-a-uocif-omoc-9002-atarp-ed-alob\/68243541\/di\/_\/ogitra\/atarp-ed-alob\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual a diferen\u00e7a que o Flamengo tirou em 2009?<\/h2>\n\n\n<p><\/p>Flamengo tirou diferen\u00e7a maior que atual para o Botafogo a 13 jogos do fim em 2009 e foi campe\u00e3o. O Flamengo visita o Corinthians neste s\u00e1bado (7), \u00e0s 21h, pela 26\u00aa rodada do Brasileir\u00e3o. Nove pontos atr\u00e1s do l\u00edder Botafogo, o time carioca ainda n\u00e3o entregou os pontos pela \u00fanica competi\u00e7\u00e3o que restou na temporada.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('orielisarb-otanoepmac-od-oaceles-a-uocif-omoc-9002-atarp-ed-alob\/68243541\/di\/_\/ogitra\/atarp-ed-alob\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Como foi a arrancada do Fluminense em 2009?<\/h2>\n\n\n<p><\/p>2009. A arrancada mais famosa da hist\u00f3ria do clube foi tamb\u00e9m a mais dram\u00e1tica, com uma s\u00e9rie de 11 jogos sem derrotas &#8211; foram sete vit\u00f3rias, sendo seis seguidas, e quatro empates. A rea\u00e7\u00e3o na reta final foi determinante para evitar o rebaixamento em uma temporada em que o Fluminense chegou a ter 98% de risco de queda.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('orielisarb-otanoepmac-od-oaceles-a-uocif-omoc-9002-atarp-ed-alob\/68243541\/di\/_\/ogitra\/atarp-ed-alob\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem foi rebaixado no Brasileir\u00e3o de 2009?<\/h2>\n\n\n<p><\/p>Personagens da fuga heroica de 2009 narram momentos de tens\u00e3o com viol\u00eancia ap\u00f3s jogo que determinou o rebaixamento do Coritiba e manteve o Flu na S\u00e9rie A. Dia 6 de dezembro de 2009. Est\u00e1dio Couto Pereira, em Curitiba. O placar mostrava 1 a 1 na partida entre Coritiba e Fluminense pela \u00faltima rodada do Brasileir\u00e3o.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('orielisarb-otanoepmac-od-oaceles-a-uocif-omoc-9002-atarp-ed-alob\/68243541\/di\/_\/ogitra\/atarp-ed-alob\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">O Sport foi rebaixado em 2009?<\/h2>\n\n\n<p><\/p>Na parte inferior da tabela, o Sport foi a primeira equipe matematicamente rebaixada para a S\u00e9rie B de 2010, ap\u00f3s empatar em 2\u20132 contra o Palmeiras em 11 de novembro e faltando tr\u00eas rodadas para o t\u00e9rmino do campeonato.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('orielisarb-otanoepmac-od-oaceles-a-uocif-omoc-9002-atarp-ed-alob\/68243541\/di\/_\/ogitra\/atarp-ed-alob\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem foi campe\u00e3o brasileiro em 2010?<\/h2>\n\n\n<p><\/p>O Bola de Prata chegou a 2010 em sua 41\u00aa edi\u00e7\u00e3o, que teve seis clubes que ficaram com os 13 trof\u00e9us entregues. O Fluminense venceu o Campeonato Brasileiro, somando 71 pontos, superando o vice Cruzeiro, que juntou apenas 69.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('orielisarb-otanoepmac-od-oaceles-a-uocif-omoc-9002-atarp-ed-alob\/68243541\/di\/_\/ogitra\/atarp-ed-alob\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quais jogadores do Flamengo foram campe\u00f5es mundiais?<\/h2>\n\nRossi, Wesley (Varela), Danilo, L\u00e9o Pereira e Ayrton Lucas; Pulgar, Jorginho, Gerson (Wallace Yan) e Arrascaeta (Bruno Henrique); Luiz Ara\u00fajo e Gonzalo Plata.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('AFIF_odnuM_od_apoC_a_arap_sodacovnoc_ognemalF_od_satageR_ed_ebulC_od_satsilobetuf_ed_atsiL\/ikiw\/gro.aidepikiw.tp\/\/:sptth'), '_blank')\">Veja a resposta completa em pt.wikipedia.org<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual jogador do Flamengo tem a Copa do Mundo?<\/h2>\n\n\n<p><\/p>Meia &#8211; Gerson (Flamengo)<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('AFIF_odnuM_od_apoC_a_arap_sodacovnoc_ognemalF_od_satageR_ed_ebulC_od_satsilobetuf_ed_atsiL\/ikiw\/gro.aidepikiw.tp\/\/:sptth'), '_blank')\">Veja a resposta completa em pt.wikipedia.org<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">O Flamengo \u00e9 reconhecido pela Fifa como campe\u00e3o mundial?<\/h2>\n\n\n<p><\/p>O documento coloca os cariocas e paulistas com uma Copa desse g\u00eanero, assim como o Flamengo, que venceu a Copa Intercontinental de 1981. O Real Madrid, por exemplo, \u00e9 listado com nove t\u00edtulos desse mesma categoria.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('AFIF_odnuM_od_apoC_a_arap_sodacovnoc_ognemalF_od_satageR_ed_ebulC_od_satsilobetuf_ed_atsiL\/ikiw\/gro.aidepikiw.tp\/\/:sptth'), '_blank')\">Veja a resposta completa em pt.wikipedia.org<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual era o time do Flamengo campe\u00e3o mundial?<\/h2>\n\n\n<p><\/p>Naquele dia, o Meng\u00e3o, comandado por Paulo C\u00e9sar Carpegiani, entrou em campo assim: Raul, Leandro, Marinho, Mozer e Junior; Andrade, Ad\u00edlio e Zico; Tita, Nunes e Lico.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('AFIF_odnuM_od_apoC_a_arap_sodacovnoc_ognemalF_od_satageR_ed_ebulC_od_satsilobetuf_ed_atsiL\/ikiw\/gro.aidepikiw.tp\/\/:sptth'), '_blank')\">Veja a resposta completa em pt.wikipedia.org<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">O que a Fifa diz sobre o Mundial do Flamengo?<\/h2>\n\n\n<p><\/p>Em relat\u00f3rio sobre os 32 clubes participantes da Copa do Mundo nos Estados Unidos, a Fifa diz que o Flamengo tem sete t\u00edtulos brasileiros e n\u00e3o contabiliza o campeonato de 1987.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('AFIF_odnuM_od_apoC_a_arap_sodacovnoc_ognemalF_od_satageR_ed_ebulC_od_satsilobetuf_ed_atsiL\/ikiw\/gro.aidepikiw.tp\/\/:sptth'), '_blank')\">Veja a resposta completa em pt.wikipedia.org<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quanto o Flamengo ganhou na Copa do mundo?<\/h2>\n\n\n<p><\/p>Flamengo soma mais de R$ 150 milh\u00f5es em premia\u00e7\u00f5es na Copa do Mundo de Clubes. flamengo.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('AFIF_odnuM_od_apoC_a_arap_sodacovnoc_ognemalF_od_satageR_ed_ebulC_od_satsilobetuf_ed_atsiL\/ikiw\/gro.aidepikiw.tp\/\/:sptth'), '_blank')\">Veja a resposta completa em pt.wikipedia.org<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem tem mais copas do mundo, Flamengo ou?<\/h2>\n\n\n<p><\/p><p>1\u00ba | Real Madrid | 5 Copa do Mundo de Clubes da FIFA 1 Copa Intercontinental da FIFA 3 Copa Intercontinental<\/p><table border=\"1\"><tr><td>31\u00ba<\/td><td>Cruzeiro<\/td><td>&#8211;<\/td><\/tr><tr><td>Flamengo<\/td><td>1 Copa Intercontinental<\/td><\/tr><tr><td>Internacional<\/td><td>1 Copa do Mundo de Clubes da FIFA<\/td><\/tr><\/table><br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('AFIF_odnuM_od_apoC_a_arap_sodacovnoc_ognemalF_od_satageR_ed_ebulC_od_satsilobetuf_ed_atsiL\/ikiw\/gro.aidepikiw.tp\/\/:sptth'), '_blank')\">Veja a resposta completa em pt.wikipedia.org<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual era o time do flamengo no Torneio Internacional do Rio de Janeiro de 1970?<\/h2>\n\nO time -base rubro negro nesta campanha era: Sidnei; Murilo, Washington, Tinho e Paulo Henrique; Liminha e Zanata; Doval, Dion\u00edsio, Fio e Ar\u00edlson. Tamb\u00e9m atuaram o goleiro Marco Aur\u00e9lio, On\u00e7a, Tinteiro, Rodrigues Neto, Ademir, Nei, Luis Carlos e Bianchini.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('0791_ed_orienaJ_ed_oiR_od_lanoicanretnI_oienroT\/ikiw\/gro.aidepikiw.tp\/\/:sptth'), '_blank')\">Veja a resposta completa em pt.wikipedia.org<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Como era o Flamengo na d\u00e9cada de 70?<\/h2>\n\n\n<p><\/p>O maior legado da d\u00e9cada de 70, foi revelar ao mundo do futebol a equipe mais vitoriosa do Flamengo, e sem d\u00favida alguma um dos maiores esquadr\u00f5es do futebol mundial. Foi nesse per\u00edodo que craques como Zico, J\u00fanior, Leandro, Andrade e outros t\u00e3o importantes quanto, subiram para a equipe profissional do Flamengo.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('0791_ed_orienaJ_ed_oiR_od_lanoicanretnI_oienroT\/ikiw\/gro.aidepikiw.tp\/\/:sptth'), '_blank')\">Veja a resposta completa em pt.wikipedia.org<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual era o time do Flamengo em 1972?<\/h2>\n\n\n<p><\/p>Flamengo: Renato, Moreira, Chiquinho Pastor, Tinho e Rodrigues Neto; Liminha e Zanata (Mineiro); Rog\u00e9rio (Caio Cambalhota) Fio, Humberto e Paulo C\u00e9zar. T\u00e9cnico: Zagallo.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('0791_ed_orienaJ_ed_oiR_od_lanoicanretnI_oienroT\/ikiw\/gro.aidepikiw.tp\/\/:sptth'), '_blank')\">Veja a resposta completa em pt.wikipedia.org<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual era o time do Flamengo em 1953?<\/h2>\n\n\n<p><\/p>Flamengo, 1953: Joel, \u00cdndio, Evaristo, Ben\u00edtez e Esquerdinha !<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('0791_ed_orienaJ_ed_oiR_od_lanoicanretnI_oienroT\/ikiw\/gro.aidepikiw.tp\/\/:sptth'), '_blank')\">Veja a resposta completa em pt.wikipedia.org<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual era o time do Flamengo em 1969?<\/h2>\n\n\n<p><\/p>Flamengo: Dominguez, Murilo, On\u00e7a, Guilherme, Paulo Henrique; Liminha, Rodrigues Neto, Arilson (Sidnei); Doval, Fio Maravilha e Dionisio. T\u00e9cnico: Tim. Fluminense: F\u00e9lix, Oliveira, Galhardo, Assis, Marco Ant\u00f4nio; Denilson, Lulinha (Samarone); Wilton, Cl\u00e1udio, Fl\u00e1vio e Lula (Gilson Nunes). T\u00e9cnico: Tel\u00ea Santana.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('0791_ed_orienaJ_ed_oiR_od_lanoicanretnI_oienroT\/ikiw\/gro.aidepikiw.tp\/\/:sptth'), '_blank')\">Veja a resposta completa em pt.wikipedia.org<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual era o nome do time do Flamengo antigamente?<\/h2>\n\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Clube de Regatas do Flamengo<\/li>\n<li> Se na \u00e9poca da funda\u00e7\u00e3o do Flamengo o remo reinava absoluto como esporte favorito dos cariocas, em pouco tempo outra modalidade come\u00e7ou a rivalizar pela prefer\u00eancia do p\u00fablico: o futebol.<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('0791_ed_orienaJ_ed_oiR_od_lanoicanretnI_oienroT\/ikiw\/gro.aidepikiw.tp\/\/:sptth'), '_blank')\">Veja a resposta completa em pt.wikipedia.org<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quais eram os jogadores antigos do Flamengo?<\/h2>\n\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>J\u00fanior \u2013 876 jogos. H\u00e1 45 anos, o nosso eterno Junior Capacete estreava com o Manto Sagrado.<\/li>\n<li>Zico \u2013 732 jogos. Foto: Masashi Hara\/Getty Images. &#8230;<\/li>\n<li>Ad\u00edlio \u2013 617 jogos. &#8230;<\/li>\n<li>Jordan \u2013 609 jogos. &#8230;<\/li>\n<li>Andrade \u2013 570 jogos. &#8230;<\/li>\n<li>Cantarele \u2013 557 jogos. &#8230;<\/li>\n<li>L\u00e9o Moura \u2013 519 jogos. &#8230;<\/li>\n<li>Carlinhos \u2013 516 jogos. &#8230;<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('0791_ed_orienaJ_ed_oiR_od_lanoicanretnI_oienroT\/ikiw\/gro.aidepikiw.tp\/\/:sptth'), '_blank')\">Veja a resposta completa em pt.wikipedia.org<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual o elenco do Flamengo 2009?<\/h2>\n\nEm 2009, o Flamengo, que terminou campe\u00e3o brasileiro com o t\u00e9cnico Andrade, tinha como base: Bruno; L\u00e9o Moura, Ronaldo Angelim, David Braz e Juan; Airton, Willians e Tor\u00f3; Z\u00e9 Roberto e Adriano.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('susej-egroj-euq-rohlem-9002-emit-ahca-euq-rop-acilpxe-nosrebelk-ognemalf\/33465141\/di\/_\/ogitra\/ognemalf\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual foi o time campe\u00e3o brasileiro de 2009?<\/h2>\n\n\n<p><\/p>O Flamengo venceu o Campeonato Brasileiro, somando 67 pontos, superando o vice Internacional, que juntou apenas 65. A equipe campe\u00e3 tamb\u00e9m colocou dois atletas na sele\u00e7\u00e3o da premia\u00e7\u00e3o.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('susej-egroj-euq-rohlem-9002-emit-ahca-euq-rop-acilpxe-nosrebelk-ognemalf\/33465141\/di\/_\/ogitra\/ognemalf\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem era o camisa 10 do Flamengo em 2009?<\/h2>\n\n\n<p><\/p>Em 2009, o Flamengo voltou ao mercado para achar um 10. E o escolhido foi o atacante Z\u00e9 Roberto, que havia se destacado pelo Botafogo e que chegou por empr\u00e9stimo do Schalke 04, da Alemanha. Por\u00e9m, ele sentiu o peso da camisa, come\u00e7ou mal e foi at\u00e9 reserva na final do Carioca, conquistado em cima do pr\u00f3prio Botafogo.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('susej-egroj-euq-rohlem-9002-emit-ahca-euq-rop-acilpxe-nosrebelk-ognemalf\/33465141\/di\/_\/ogitra\/ognemalf\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual era o elenco do Flamengo em 2010?<\/h2>\n\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Goleiros. Marcelo Carn\u00e9 Marcelo Lomba. Paulo Victor. Vin\u00edcius. Laterais direitos. Everton Silva. Leonardo Moura. &#8230;<\/li>\n<li>Laterais esquerdos. Jorbison. Juan. Rodrigo Alvim. Zagueiros. David. Fabr\u00edcio. Jean. &#8230;<\/li>\n<li>Volantes. Corr\u00eaa. Fernando. L\u00e9o Medeiros. Lenon. Maldonado. R\u00f4mulo. &#8230;<\/li>\n<li>Michael. Petkovic. Ram\u00f3n. Vin\u00edcius Pacheco. V\u00edtor Saba. Atacantes. Borja.<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('susej-egroj-euq-rohlem-9002-emit-ahca-euq-rop-acilpxe-nosrebelk-ognemalf\/33465141\/di\/_\/ogitra\/ognemalf\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem eram os jogadores do Flamengo em 2009?<\/h2>\n\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Campeonato Brasileiro de 2009<\/li>\n<li> Diego, Everton Silva, Welinton, David, Lenon, Kl\u00e9berson, Fierro, D\u00eanis Marques, Bruno Mezenga.<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('susej-egroj-euq-rohlem-9002-emit-ahca-euq-rop-acilpxe-nosrebelk-ognemalf\/33465141\/di\/_\/ogitra\/ognemalf\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quando Kleberson jogou no Flamengo?<\/h2>\n\n\n<p><\/p>Retornou ao futebol brasileiro em 2005, jogando pelo Flamengo e depois pelo Bahia, onde teve bons momentos. Kl\u00e9berson tamb\u00e9m teve passagens pelo futebol norte-americano, defendendo equipes como Philadelphia Union e Fort Lauderdale Strikers.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('susej-egroj-euq-rohlem-9002-emit-ahca-euq-rop-acilpxe-nosrebelk-ognemalf\/33465141\/di\/_\/ogitra\/ognemalf\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual era o elenco do Flamengo em 2011?<\/h2>\n\n<p>Nome | POS<\/p><table border=\"1\"><tr><td>Dar\u00edo Bottinelli<\/td><td>M<\/td><\/tr><tr><td>Dejan Petkovic<\/td><td>M<\/td><\/tr><tr><td>Maldonado<\/td><td>M<\/td><\/tr><tr><td>Fernando<\/td><td>M<\/td><\/tr><\/table><br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmth.1102-1002-sacoirac-son-saepmac-sahnapmac-erbmeler-recnev-recnev-recnev\/ognemalf\/rb.moc.ecnal.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.lance.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Em que time o Ronaldinho estava em 2011?<\/h2>\n\n\n<p><\/p>No Brasileir\u00e3o de 2011, o Bruxo cobrou esta falta rasteira na vit\u00f3ria memor\u00e1vel do Flamengo por 5 a 4 contra o Santos, na Vila Belmiro. No ano seguinte, com a camisa do Galo, repetiu a dose na goleada por 6 a 0 diante do Figueirense, na Arena Independ\u00eancia.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmth.1102-1002-sacoirac-son-saepmac-sahnapmac-erbmeler-recnev-recnev-recnev\/ognemalf\/rb.moc.ecnal.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.lance.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual era o elenco do Flamengo de 2012?<\/h2>\n\n\n<p><\/p><p># | Jogadores | Idade<\/p><table border=\"1\"><tr><td>44<\/td><td>Alex Silva Zagueiro<\/td><td>25<\/td><\/tr><tr><td>3<\/td><td>Welinton Zagueiro<\/td><td>21<\/td><\/tr><tr><td>14<\/td><td>David Braz Zagueiro<\/td><td>23<\/td><\/tr><tr><td>4<\/td><td>Marcos Gonz\u00e1lez Zagueiro<\/td><td>30<\/td><\/tr><\/table><br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmth.1102-1002-sacoirac-son-saepmac-sahnapmac-erbmeler-recnev-recnev-recnev\/ognemalf\/rb.moc.ecnal.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.lance.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual era o time do Vasco em 2011?<\/h2>\n\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Prass, Allan, Ded\u00e9, Anderson Martins, Ramon, R\u00f4mulo, Eduardo Costa, Felipe, Diego Souza, Eder Luis e Alecsandro.<\/li>\n<li>Prass, Allan, Ded\u00e9, Anderson Martins, Jumar, R\u00f4mulo, Eduardo Costa, Bernardo, Diego Souza, Eder Luis e Alecsandro.<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmth.1102-1002-sacoirac-son-saepmac-sahnapmac-erbmeler-recnev-recnev-recnev\/ognemalf\/rb.moc.ecnal.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.lance.com.br<\/span><\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Goleiro Bruno; L\u00e9o Moura, \u00c1lvaro, Ronaldo Angelim, Juan (\u00c9verton); Maldonado (Tor\u00f3), Airton, Willians, Petkovi\u0107; Z\u00e9 Roberto (Emerson) e Adriano. t\u00e9cnico: Andrade. Diego, Everton Silva, Welinton, David, Lenon, Kl\u00e9berson, Fierro, D\u00eanis Marques, Bruno Mezenga. Qual era o time do Flamengo em 2010? Nome | POS Marcelo Lomba G Vin\u00edcius G Paulo Victor G Marcelo Carn\u00e9 G [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[43],"tags":[],"class_list":["post-3295","post","type-post","status-publish","format-standard","hentry","category-perguntas-frequentes"],"_links":{"self":[{"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts\/3295","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/comments?post=3295"}],"version-history":[{"count":1,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts\/3295\/revisions"}],"predecessor-version":[{"id":3296,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts\/3295\/revisions\/3296"}],"wp:attachment":[{"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/media?parent=3295"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/categories?post=3295"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/tags?post=3295"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}