{"id":3279,"date":"2025-06-25T08:10:58","date_gmt":"2025-06-25T08:10:58","guid":{"rendered":"http:\/\/385ce520-b66a-457b-8bdb-7ba84c584491"},"modified":"2025-06-25T08:10:58","modified_gmt":"2025-06-25T08:10:58","slug":"escalacao-do-fluminense-de-hoje","status":"publish","type":"post","link":"https:\/\/tsports.app.br\/perguntas-frequentes\/escalacao-do-fluminense-de-hoje\/","title":{"rendered":"Escala\u00e7\u00e3o do fluminense de hoje"},"content":{"rendered":"\n\n<h2 class=\"wp-block-heading\">Qual a escala\u00e7\u00e3o do Fluminense para o jogo de hoje?<\/h2>\n\nEscala\u00e7\u00e3o prov\u00e1vel: Fabio; Guga, Thiago Silva, Freytes, Fuentes (Ren\u00ea), Martinelli, H\u00e9rcules, Ganso; Arias, Canobbio, Cano. Quem est\u00e1 fora: Ot\u00e1vio (tend\u00e3o de Aquiles) e Soteldo (les\u00e3o muscular). Pendurados: Martinelli e Nonato.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('sebulc-ed-laidnum-seocalacse-setiplap-oiraroh-oviv-oa-ritsissa-edno-snwodnus-idolemam-x-esnenimulf\/09564351\/di\/_\/ogitra\/sebulc-ed-laidnum\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual a escala\u00e7\u00e3o do time do Fluminense para o jogo de hoje?<\/h2>\n\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Escala\u00e7\u00e3o do Fluminense<\/li>\n<li> Prov\u00e1vel escala\u00e7\u00e3o: F\u00e1bio; Guga, Thiago Silva, Freytes, Fuentes (Ren\u00ea), Martinelli, H\u00e9rcules, Ganso; Arias, Canobbio, Cano. T\u00e9cnico: Renato Ga\u00facho.<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('sebulc-ed-laidnum-seocalacse-setiplap-oiraroh-oviv-oa-ritsissa-edno-snwodnus-idolemam-x-esnenimulf\/09564351\/di\/_\/ogitra\/sebulc-ed-laidnum\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual a escala\u00e7\u00e3o do Juventude para o jogo de hoje?<\/h2>\n\n\n<p><\/p>Prov\u00e1vel time: Marc\u00e3o; Ewerthon, Rodrigo Sam, Marcos Paulo (Wilker \u00c1ngel) e Alan Ruschel; Ca\u00edque, Daniel Peixoto (Giraldo), Mandaca (Nen\u00ea); Batalla, Giovanny e Gilberto (Taliari).<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('sebulc-ed-laidnum-seocalacse-setiplap-oiraroh-oviv-oa-ritsissa-edno-snwodnus-idolemam-x-esnenimulf\/09564351\/di\/_\/ogitra\/sebulc-ed-laidnum\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem fez o gol do Fluminense no jogo de hoje?<\/h2>\n\n\n<p><\/p>Keno comemora o quarto gol do Fluminense sobre o Ulsan HD. MARCELO GON\u00c7ALVES \/ FLUMINENSE F.C. Nonato comemora o segundo gol do Fluminense sobre o Ulsan HD.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('sebulc-ed-laidnum-seocalacse-setiplap-oiraroh-oviv-oa-ritsissa-edno-snwodnus-idolemam-x-esnenimulf\/09564351\/di\/_\/ogitra\/sebulc-ed-laidnum\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem \u00e9 o 11 do Fluminense?<\/h2>\n\n\n<p>Elenco &#8211; Fluminense<\/p><p>Nome | POS<\/p><table border=\"1\"><tr><td>Kelwin<\/td><td>A<\/td><\/tr><tr><td>Everaldo9<\/td><td>A<\/td><\/tr><tr><td>Keno11<\/td><td>A<\/td><\/tr><tr><td>Germ\u00e1n Cano14<\/td><td>A<\/td><\/tr><\/table><br \/>\n\n\n\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('cf_esnenimulf.arb\/5443\/di\/_\/ocnele\/emit\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem s\u00e3o os titulares do Fluminense?<\/h2>\n\n\n<p><\/p>Escala\u00e7\u00e3o prov\u00e1vel: F\u00e1bio, Guga, Thiago Silva, Freytes e Fuentes (Ren\u00ea); H\u00e9rcules, Martinelli e Ganso; Arias, Canobbio e Cano.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('cf_esnenimulf.arb\/5443\/di\/_\/ocnele\/emit\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem \u00e9 o jogador mais famoso do Fluminense?<\/h2>\n\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Renato Ga\u00facho.<\/li>\n<li>Rivellino.<\/li>\n<li>Romerito.<\/li>\n<li>Tato.<\/li>\n<li>Tel\u00ea Santana.<\/li>\n<li>Thiago Silva.<\/li>\n<li>Waldo.<\/li>\n<li>Washington.<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('cf_esnenimulf.arb\/5443\/di\/_\/ocnele\/emit\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual foi a escala\u00e7\u00e3o do Fluminense hoje?<\/h2>\n\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>ESCALA\u00c7\u00c3O DE FLUMINENSE E ULSAN HD<\/li>\n<li> FLUMINENSE &#8211; F\u00e1bio; Samuel Xavier, Freytes, Thiago Silva e Ren\u00ea; Thiago Santos, Martinelli e Ganso (Nonato); Jhon Arias, Serna e Cano.<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('cf_esnenimulf.arb\/5443\/di\/_\/ocnele\/emit\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quanto ganha um atleta da base do Fluminense?<\/h2>\n\n\n<p><\/p>Como lhe parece a faixa de sal\u00e1rio base m\u00e9dio de R$ 139 mil-R$ 150 mil\/ano ?<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('cf_esnenimulf.arb\/5443\/di\/_\/ocnele\/emit\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem est\u00e1 no elenco do Fluminense?<\/h2>\n\n\n<p><\/p><p>Elenco atual do Fluminense Football Clubb<\/p><table border=\"1\"><tr><td>6<\/td><td>LE<\/td><td>Ren\u00ea<\/td><\/tr><tr><td>7<\/td><td>A<\/td><td>Yeferson Soteldo<\/td><\/tr><tr><td>8<\/td><td>V<\/td><td>Martinelli<\/td><\/tr><tr><td>9<\/td><td>A<\/td><td>Everaldo<\/td><\/tr><\/table><br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('cf_esnenimulf.arb\/5443\/di\/_\/ocnele\/emit\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quantas vezes o Fluminense caiu para a S\u00e9rie B?<\/h2>\n\n\n<p><\/p>J\u00e1 est\u00e1 pronto um plano para al\u00e7ar o Fluminense de volta \u00e0 primeira divis\u00e3o do Brasileiro. Rebaixado tr\u00eas vezes em tr\u00eas anos, o clube conta com apoio do Clube dos 13, que re\u00fane os 16 principais times do Brasil, para uma nova virada de mesa.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('cf_esnenimulf.arb\/5443\/di\/_\/ocnele\/emit\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 o nome do time que o Fluminense vai jogar hoje?<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pr\u00f3ximos jogos do Fluminense :<\/li>\n<li> 21\/06, 19h00 \u2013 Fluminense x Ulsan \u2013 Globo, Sportv e Caz\u00e9TV.<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('sebulc-ed-laidnum-seocalacse-setiplap-oiraroh-oviv-oa-ritsissa-edno-snwodnus-idolemam-x-esnenimulf\/09564351\/di\/_\/ogitra\/sebulc-ed-laidnum\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual o nome do time que o Fluminense vai jogar hoje?<\/h2>\n\n\n<p><\/p>Neste s\u00e1bado (21), o Fluminense enfrenta o Ulsan HD, \u00e0s 19h (de Bras\u00edlia), pela 2\u00aa rodada do Grupo F do Mundial de Clubes.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('sebulc-ed-laidnum-seocalacse-setiplap-oiraroh-oviv-oa-ritsissa-edno-snwodnus-idolemam-x-esnenimulf\/09564351\/di\/_\/ogitra\/sebulc-ed-laidnum\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 a escala\u00e7\u00e3o do Fluminense para o jogo de hoje?<\/h2>\n\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Escala\u00e7\u00e3o do Fluminense<\/li>\n<li> Prov\u00e1vel escala\u00e7\u00e3o: F\u00e1bio; Guga, Thiago Silva, Freytes, Fuentes (Ren\u00ea), Martinelli, H\u00e9rcules, Ganso; Arias, Canobbio, Cano. T\u00e9cnico: Renato Ga\u00facho.<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('sebulc-ed-laidnum-seocalacse-setiplap-oiraroh-oviv-oa-ritsissa-edno-snwodnus-idolemam-x-esnenimulf\/09564351\/di\/_\/ogitra\/sebulc-ed-laidnum\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">O que o Fluminense precisa para se classificar no Mundial?<\/h2>\n\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>O que o Fluminense precisa para classificar no Mundial:<\/li>\n<li> Se vencer o Mamelodi Sundowns: classifica em 1\u00ba ou 2\u00ba lugar, dependendo do resultado do Borussia Dortmund. Se os alem\u00e3es trope\u00e7arem, o Fluminense ser\u00e1 l\u00edder.<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('sebulc-ed-laidnum-seocalacse-setiplap-oiraroh-oviv-oa-ritsissa-edno-snwodnus-idolemam-x-esnenimulf\/09564351\/di\/_\/ogitra\/sebulc-ed-laidnum\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual est\u00e1dio vai ser o jogo do Fluminense hoje?<\/h2>\n\n\n<p><\/p>Equipes se enfrentam neste s\u00e1bado (21), \u00e0s 19h, no MetLife Stadium.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('sebulc-ed-laidnum-seocalacse-setiplap-oiraroh-oviv-oa-ritsissa-edno-snwodnus-idolemam-x-esnenimulf\/09564351\/di\/_\/ogitra\/sebulc-ed-laidnum\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Que horas \u00e9 o jogo do Fluminense hoje?<\/h2>\n\n\n<p><\/p>Fluminense e Mamelodi Sundowns se enfrentam nesta quarta-feira (25), \u00e0s 16h (hor\u00e1rio de Bras\u00edlia), Est\u00e1dio Hard Rock, em Miami.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('sebulc-ed-laidnum-seocalacse-setiplap-oiraroh-oviv-oa-ritsissa-edno-snwodnus-idolemam-x-esnenimulf\/09564351\/di\/_\/ogitra\/sebulc-ed-laidnum\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual pa\u00eds \u00e9 o time Ulsan Hyundai?<\/h2>\n\n\n<p><\/p>O Ulsan HD, da Coreia do Sul, \u00e9 um dos advers\u00e1rios do Fluminense no Grupo F da Copa do Mundo de Clubes. A equipe, contudo, nem sempre teve esse nome. Fundado em 1983, o clube sul-coreano teve parceria com a Hyundai, uma das principais montadoras de ve\u00edculos do Oriente.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('sebulc-ed-laidnum-seocalacse-setiplap-oiraroh-oviv-oa-ritsissa-edno-snwodnus-idolemam-x-esnenimulf\/09564351\/di\/_\/ogitra\/sebulc-ed-laidnum\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quais s\u00e3o as notas dos jogadores do Fluminense hoje?<\/h2>\n\n\n<p>Ranking de Atua\u00e7\u00e3o<\/p>\n\n<ul class=\"wp-block-list\">\n<li>1\u00ba F\u00e1bio &#8211; GOL. nota ge 6.0. p\u00fablico 6.0. &#8230;<\/li>\n<li>2\u00ba Guga &#8211; LAT. nota ge 5.5. p\u00fablico 5.5. &#8230;<\/li>\n<li>3\u00ba Samuel Xavier &#8211; LAT. nota ge &#8212; p\u00fablico &#8212; &#8230;<\/li>\n<li>4\u00ba Thiago Silva &#8211; ZAG. nota ge 5.5. p\u00fablico 5.5. &#8230;<\/li>\n<li>5\u00ba Freytes &#8211; ZAG. nota ge 5.5. &#8230;<\/li>\n<li>6\u00ba Gabriel Fuentes &#8211; LAT. nota ge 5.5. &#8230;<\/li>\n<li>7\u00ba Martinelli &#8211; MEI. nota ge 5.5. &#8230;<\/li>\n<li>8\u00ba Nonato &#8211; MEI. nota ge 7.5.<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.saton-saus-ed-naslu-o-artnoc-serohlem-so-oas-otanon-e-onek-esnenimulf-od-seocauta\/12\/60\/5202\/aiciton\/esnenimulf\/semit\/lobetuf\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual a escala\u00e7\u00e3o do Fluminense hoje \u00e0 noite?<\/h2>\n\n\n<p><\/p>Escala\u00e7\u00e3o prov\u00e1vel: F\u00e1bio, Guga, Thiago Silva, Freytes e Fuentes (Ren\u00ea); H\u00e9rcules, Martinelli e Ganso; Arias, Canobbio e Cano.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.saton-saus-ed-naslu-o-artnoc-serohlem-so-oas-otanon-e-onek-esnenimulf-od-seocauta\/12\/60\/5202\/aiciton\/esnenimulf\/semit\/lobetuf\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem \u00e9 o melhor jogador do Fluminense atualmente?<\/h2>\n\n\n<p><\/p>Estrelas do Mundial: Jhon Arias, do Fluminense, \u00e9 o colombiano mais amado do Brasil. O vers\u00e1til jogador de 27 anos \u00e9 uma das estrelas do Tricolor para a disputa do Mundial de Clubes da FIFA 2025\u2122.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.saton-saus-ed-naslu-o-artnoc-serohlem-so-oas-otanon-e-onek-esnenimulf-od-seocauta\/12\/60\/5202\/aiciton\/esnenimulf\/semit\/lobetuf\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 a poss\u00edvel escala\u00e7\u00e3o do Fluminense para hoje?<\/h2>\n\n\n<p><\/p>Escala\u00e7\u00e3o prov\u00e1vel: F\u00e1bio, Samuel Xavier, Thiago Silva, Freytes e Ren\u00ea; H\u00e9rcules, Martinelli e Nonato; Arias, Canobbio (Serna) e Everaldo. O Fluminense enfrenta, al\u00e9m do Borussia, Ulsan HD e Mamelodi Sundowns nas outras partidas do Grupo F da Copa de Clubes.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.saton-saus-ed-naslu-o-artnoc-serohlem-so-oas-otanon-e-onek-esnenimulf-od-seocauta\/12\/60\/5202\/aiciton\/esnenimulf\/semit\/lobetuf\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quais s\u00e3o as notas dos jogadores do Fluminense?<\/h2>\n\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>1\u00ba F\u00e1bio &#8211; GOL. nota ge 7.0. p\u00fablico 7.0. &#8230;<\/li>\n<li>2\u00ba Samuel Xavier &#8211; LAT. nota ge 6.5. p\u00fablico 6.5. &#8230;<\/li>\n<li>3\u00ba Thiago Silva &#8211; ZAG. nota ge 7.5. p\u00fablico 7.5. &#8230;<\/li>\n<li>4\u00ba Freytes &#8211; ZAG. nota ge 7.0. p\u00fablico 7.0. &#8230;<\/li>\n<li>5\u00ba Ren\u00ea &#8211; LAT. nota ge 6.5. p\u00fablico 6.5. &#8230;<\/li>\n<li>6\u00ba Martinelli &#8211; MEI. nota ge 8.0. &#8230;<\/li>\n<li>7\u00ba Lima &#8211; MEI. nota ge 5.5. &#8230;<\/li>\n<li>8\u00ba H\u00e9rcules &#8211; MEI. nota ge 6.5.<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.saton-saus-ed-naslu-o-artnoc-serohlem-so-oas-otanon-e-onek-esnenimulf-od-seocauta\/12\/60\/5202\/aiciton\/esnenimulf\/semit\/lobetuf\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem s\u00e3o os pontas do Fluminense?<\/h2>\n\n\n<p><\/p><p># | Jogadores | Idade<\/p><table border=\"1\"><tr><td>19<\/td><td>Joaqu\u00edn Lavega Ponta Esquerda<\/td><td>20<\/td><\/tr><tr><td>77<\/td><td>Paulo Baya Ponta Esquerda<\/td><td>25<\/td><\/tr><tr><td>11<\/td><td>Keno Ponta Esquerda<\/td><td>35<\/td><\/tr><tr><td>21<\/td><td>Jhon Arias Ponta Direita<\/td><td>27<\/td><\/tr><\/table><br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.saton-saus-ed-naslu-o-artnoc-serohlem-so-oas-otanon-e-onek-esnenimulf-od-seocauta\/12\/60\/5202\/aiciton\/esnenimulf\/semit\/lobetuf\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem \u00e9 o camisa 9 do Fluminense?<\/h2>\n\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>O 9 que n\u00e3o \u00e9 9<\/li>\n<li> Ainda que nunca tenha usado o n\u00famero, Cano est\u00e1 no rol de grandes camisas nove, no sentido simb\u00f3lico, da hist\u00f3ria do clube.<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.saton-saus-ed-naslu-o-artnoc-serohlem-so-oas-otanon-e-onek-esnenimulf-od-seocauta\/12\/60\/5202\/aiciton\/esnenimulf\/semit\/lobetuf\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 a escala\u00e7\u00e3o do Internacional para o jogo de hoje?<\/h2>\n\nProv\u00e1vel Inter: Anthoni; Aguirre, Vit\u00e3o, Juninho e Ramon; Fernando, Thiago Maia, Alan Patrick, Gustavo Prado (Vitinho) e Wesley; Borr\u00e9 (Lucca).<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('oarielisarb-seocalacse-sievavorp-setiplap-oiraroh-oviv-oa-ritsissa-edno-esnenimulf-lanoicanretni\/46715251\/di\/_\/ogitra\/oarielisarb\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual a escala\u00e7\u00e3o do Internacional para o jogo de hoje?<\/h2>\n\n\n<p><\/p>A prov\u00e1vel escala\u00e7\u00e3o da Inter \u00e9: Sommer; Pavard, Acerbi e Bastoni; Dumfries, Barella, Asllani, Mkhitaryan e Dimarco; Thuram e Lautaro Mart\u00ednez.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('oarielisarb-seocalacse-sievavorp-setiplap-oiraroh-oviv-oa-ritsissa-edno-esnenimulf-lanoicanretni\/46715251\/di\/_\/ogitra\/oarielisarb\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quais s\u00e3o os desfalques do Internacional para o jogo de hoje?<\/h2>\n\n\n<p><\/p>Atualmente, est\u00e3o fora por algum problema cl\u00ednico Rochet, Bruno Gomes, Gabriel Mercado, Victor Gabriel, Bernabei, Fernando, Carbonero, Borr\u00e9, Vitinho, Enner Valencia, Ricardo Mathias e Lucca Drummond.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('oarielisarb-seocalacse-sievavorp-setiplap-oiraroh-oviv-oa-ritsissa-edno-esnenimulf-lanoicanretni\/46715251\/di\/_\/ogitra\/oarielisarb\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual a escala\u00e7\u00e3o do time do Inter de Miami para o jogo de hoje?<\/h2>\n\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>ESCALA\u00c7\u00c3O DO INTER MIAMI<\/li>\n<li> INTER MIAMI: Ustari; Fray, Falcon, Aviles (Luj\u00e1n) e Allen (Jordi Alba); Allende, Cremaschi, Busquets e Segovia; Messi e Su\u00e1rez.<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('oarielisarb-seocalacse-sievavorp-setiplap-oiraroh-oviv-oa-ritsissa-edno-esnenimulf-lanoicanretni\/46715251\/di\/_\/ogitra\/oarielisarb\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 a prov\u00e1vel escala\u00e7\u00e3o do Internacional?<\/h2>\n\n\n<p><\/p>Prov\u00e1vel Inter: Anthoni; Aguirre, Vit\u00e3o, Juninho e Ramon; Fernando, Thiago Maia, Alan Patrick, Gustavo Prado (Vitinho) e Wesley; Borr\u00e9 (Lucca).<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('oarielisarb-seocalacse-sievavorp-setiplap-oiraroh-oviv-oa-ritsissa-edno-esnenimulf-lanoicanretni\/46715251\/di\/_\/ogitra\/oarielisarb\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 o time Internacional que joga hoje?<\/h2>\n\n\n<p><\/p><p>DATA | Jogo | HORA<\/p><table border=\"1\"><tr><td>s\u00e1b., 9 ago.<\/td><td>BRA<\/td><td>A definir<\/td><\/tr><tr><td>qua., 13 ago.<\/td><td>FLA<\/td><td>17:30<\/td><\/tr><tr><td>s\u00e1b., 16 ago.<\/td><td>INT<\/td><td>A definir<\/td><\/tr><tr><td>qua., 20 ago.<\/td><td>INT<\/td><td>17:30<\/td><\/tr><\/table><br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('oarielisarb-seocalacse-sievavorp-setiplap-oiraroh-oviv-oa-ritsissa-edno-esnenimulf-lanoicanretni\/46715251\/di\/_\/ogitra\/oarielisarb\/lobetuf\/rb.moc.npse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.espn.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual a escala\u00e7\u00e3o do Atl\u00e9tico Mineiro para o jogo de hoje?<\/h2>\n\nO prov\u00e1vel time neste domingo \u00e9: Everson; Natanael, Lyanco, Alonso e Rubens; Alan Franco, Patrick, Igor Gomes (Gabriel Menino) e Gustavo Scarpa; Rony e Hulk.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.acuc-moc-enuer-es-ninem-araec-raracne-arap-euqata-on-axiab-met-emit-gm-ocitelta-od-oacalacse\/13\/50\/5202\/aiciton\/gm-ocitelta\/semit\/lobetuf\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual a escala\u00e7\u00e3o do Atl\u00e9tico para o jogo de hoje?<\/h2>\n\n\n<p><\/p>A prov\u00e1vel escala\u00e7\u00e3o do Atleti tem: Oblak; Llorente, Le Normand, Lenglet e Galan; Barrios, De Paul, Koke e Giuliano Simeone; Juli\u00e1n Alvarez e Sorloth (Griezmann).<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.acuc-moc-enuer-es-ninem-araec-raracne-arap-euqata-on-axiab-met-emit-gm-ocitelta-od-oacalacse\/13\/50\/5202\/aiciton\/gm-ocitelta\/semit\/lobetuf\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual o time titular do Atl\u00e9tico Mineiro?<\/h2>\n\n\n<p><\/p><p>Nome | POS<\/p><table border=\"1\"><tr><td>David Kau\u00e350<\/td><td>D<\/td><\/tr><tr><td>Paulo Vitor<\/td><td>M<\/td><\/tr><tr><td>Fausto Vera8<\/td><td>M<\/td><\/tr><tr><td>Gustavo Scarpa10<\/td><td>M<\/td><\/tr><\/table><br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.acuc-moc-enuer-es-ninem-araec-raracne-arap-euqata-on-axiab-met-emit-gm-ocitelta-od-oacalacse\/13\/50\/5202\/aiciton\/gm-ocitelta\/semit\/lobetuf\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Onde assistir o jogo do Atl\u00e9tico Mineiro hoje?<\/h2>\n\n\n<p><\/p>A partida ter\u00e1 transmiss\u00e3o ao vivo pelo Premiere, na Globo (Minas Gerais e Rio Grande do Sul), al\u00e9m de tempo real do CNN Esportes.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.acuc-moc-enuer-es-ninem-araec-raracne-arap-euqata-on-axiab-met-emit-gm-ocitelta-od-oacalacse\/13\/50\/5202\/aiciton\/gm-ocitelta\/semit\/lobetuf\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Qual a escala\u00e7\u00e3o do Fluminense para o jogo de hoje? Escala\u00e7\u00e3o prov\u00e1vel: Fabio; Guga, Thiago Silva, Freytes, Fuentes (Ren\u00ea), Martinelli, H\u00e9rcules, Ganso; Arias, Canobbio, Cano. Quem est\u00e1 fora: Ot\u00e1vio (tend\u00e3o de Aquiles) e Soteldo (les\u00e3o muscular). Pendurados: Martinelli e Nonato. Qual a escala\u00e7\u00e3o do time do Fluminense para o jogo de hoje? Qual a escala\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[43],"tags":[],"class_list":["post-3279","post","type-post","status-publish","format-standard","hentry","category-perguntas-frequentes"],"_links":{"self":[{"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts\/3279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/comments?post=3279"}],"version-history":[{"count":1,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts\/3279\/revisions"}],"predecessor-version":[{"id":3280,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts\/3279\/revisions\/3280"}],"wp:attachment":[{"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/media?parent=3279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/categories?post=3279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/tags?post=3279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}