{"id":3275,"date":"2025-06-25T08:08:11","date_gmt":"2025-06-25T08:08:11","guid":{"rendered":"http:\/\/bc192ad9-87e0-4553-b854-02532b46efda"},"modified":"2025-06-25T08:08:11","modified_gmt":"2025-06-25T08:08:11","slug":"escalacao-do-corinthians-x-criciuma","status":"publish","type":"post","link":"https:\/\/tsports.app.br\/perguntas-frequentes\/escalacao-do-corinthians-x-criciuma\/","title":{"rendered":"Escala\u00e7\u00e3o do corinthians x crici\u00fama"},"content":{"rendered":"Time prov\u00e1vel: Gustavo; Dudu, Rodrigo, Tobias Figueiredo e Marcelo Hermes; Barreto, Newton, Ronald e Matheusinho (Fellipe Mateus); Bolasie e Felipe Vizeu (Pedro Rocha). Quem est\u00e1 fora: Ningu\u00e9m. Pendurados: Alisson, Fellipe Mateus, Gustavo, Jonathan, Newton e Tobias Figueiredo.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.seocalacse-e-oiraroh-oviv-oa-ritsissa-edno-snaihtniroc-x-amuicirc\/03\/11\/4202\/aiciton\/a-eires-oarielisarb\/lobetuf\/cs\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual foi a escala\u00e7\u00e3o do Corinthians contra o Crici\u00fama?<\/h2>\n\nPara encarar o Crici\u00fama o Corinthians contar\u00e1 com o retorno de Memphis Depay, que cumpriu suspens\u00e3o na \u00faltima rodada. Uma poss\u00edvel escala\u00e7\u00e3o alvinegra \u00e9: Hugo Souza, Matheuzinho, Andr\u00e9 Ramalho, Gustavo Henrique e Matheus Bidu; Raniele (Jos\u00e9 Mart\u00ednez), Carrillo, Breno Bidon e Garro; Memphis Depay e Yuri Alberto.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.seocalacse-e-oiraroh-oviv-oa-ritsissa-edno-snaihtniroc-x-amuicirc\/03\/11\/4202\/aiciton\/a-eires-oarielisarb\/lobetuf\/cs\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual a escala\u00e7\u00e3o do Corinthians contra o Crici\u00fama?<\/h2>\n\n\n<p><\/p>Sendo assim, a escala\u00e7\u00e3o do Corinthians ser\u00e1: Hugo Souza, Matheuzinho, Andr\u00e9 Ramalho, Gustavo Henrique e Matheus Bidu; Raniele (Jos\u00e9 Mart\u00ednez), Carrillo, Breno Bidon e Garro; Memphis Depay e Yuri Alberto.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.seocalacse-e-oiraroh-oviv-oa-ritsissa-edno-snaihtniroc-x-amuicirc\/03\/11\/4202\/aiciton\/a-eires-oarielisarb\/lobetuf\/cs\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem foi escalado para o jogo do Corinthians hoje?<\/h2>\n\n\n<p><\/p>Sendo assim, o Tim\u00e3o est\u00e1 escalado com: Hugo Souza, L\u00e9o Man\u00e1, Andr\u00e9 Ramalho, Jo\u00e3o Pedro Tchoca e Matheus Bidu; Ryan, Charles, Alex Santana e \u00c1ngel Romero; Talles Magno e H\u00e9ctor Hern\u00e1ndez.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.seocalacse-e-oiraroh-oviv-oa-ritsissa-edno-snaihtniroc-x-amuicirc\/03\/11\/4202\/aiciton\/a-eires-oarielisarb\/lobetuf\/cs\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Como saiu o jogo Corinthians-C Crici\u00fama?<\/h2>\n\n\n<p><\/p>O Corinthians venceu o Crici\u00fama por 4 a 2 de virada, neste s\u00e1bado, no Heriberto H\u00fclse, em jogo v\u00e1lido pela 36\u00aa rodada do Brasileir\u00e3o (confira abaixo os melhores momentos).<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.seocalacse-e-oiraroh-oviv-oa-ritsissa-edno-snaihtniroc-x-amuicirc\/03\/11\/4202\/aiciton\/a-eires-oarielisarb\/lobetuf\/cs\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem \u00e9 favorito entre Corinthians e Crici\u00fama?<\/h2>\n\n\n<p><\/p>Crici\u00fama x Corinthians Palpite e Progn\u00f3stico &#8211; Corinthians empate anula aposta. Crici\u00fama e Corinthians se enfrentam com objetivos distintos nesta partida, enquanto o time do Crici\u00fama precisa vencer para tentar se manter na primeira divis\u00e3o, o tim\u00e3o precisa vencer para tentar uma vaga na Libertadores.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.seocalacse-e-oiraroh-oviv-oa-ritsissa-edno-snaihtniroc-x-amuicirc\/03\/11\/4202\/aiciton\/a-eires-oarielisarb\/lobetuf\/cs\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual o prov\u00e1vel escal\u00e3o do Corinthians para hoje?<\/h2>\n\nSendo assim, a prov\u00e1vel escala\u00e7\u00e3o do Corinthians tem: Hugo Souza; Matheuzinho, Andr\u00e9 Ramalho, Cac\u00e1 e Fabrizio Angileri; Maycon, Raniele, Andr\u00e9 Carrillo e Igor Coronado; Memphis Depay e Romero (Talles Magno). Siga o canal da Jovem Pan News e receba as principais not\u00edcias no seu WhatsApp!<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmth.nacaruh-o-artnoc-oasiced-arap-emit-enifed-lavirod-snaihtniroc-od-oacalacse\/snaihtniroc\/lobetuf\/setropse\/rb.moc.napmevoj\/\/:sptth'), '_blank')\">Veja a resposta completa em jovempan.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual o prov\u00e1vel escal\u00e3o do Corinthians hoje?<\/h2>\n\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Escala\u00e7\u00e3o do Tim\u00e3o<\/li>\n<li> Prov\u00e1vel escala\u00e7\u00e3o : Matheus Donelli, Matheuzinho, Andr\u00e9 Ramalho, F\u00e9lix Torres e Matheus Bidu; Jos\u00e9 Mart\u00ednez, Ryan e Maycon; Romero, H\u00e9ctor Hern\u00e1ndez e Talles Magno.<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmth.nacaruh-o-artnoc-oasiced-arap-emit-enifed-lavirod-snaihtniroc-od-oacalacse\/snaihtniroc\/lobetuf\/setropse\/rb.moc.napmevoj\/\/:sptth'), '_blank')\">Veja a resposta completa em jovempan.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual a escala\u00e7\u00e3o do Corinthians para o jogo de hoje?<\/h2>\n\n\n<p><\/p>Escala\u00e7\u00e3o confirmada do Corinthians: Hugo Souza; Matheuzinho; Andr\u00e9 Ramalho, Cac\u00e1 e Fabrizio Angileri; Maycon; Ryan, Breno Bidon e Rodrigo Garro; Talles Magno e H\u00e9ctor Hern\u00e1ndez. T\u00e9cnico: Dorival J\u00fanior.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmth.nacaruh-o-artnoc-oasiced-arap-emit-enifed-lavirod-snaihtniroc-od-oacalacse\/snaihtniroc\/lobetuf\/setropse\/rb.moc.napmevoj\/\/:sptth'), '_blank')\">Veja a resposta completa em jovempan.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 o palpite para o jogo do Corinthians hoje?<\/h2>\n\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Palpites no Corinthians hoje<\/li>\n<li> Apesar de jogar fora de casa e diante de uma equipe que tem mostrado poder de recupera\u00e7\u00e3o no campeonato, a expectativa \u00e9 de que o Corinthians fa\u00e7a um bom jogo na Arena do Gr\u00eamio. Por isso, nosso palpite \u00e9 um empate em 1 a 1, que tem odds de 6.30 na Betano.<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmth.nacaruh-o-artnoc-oasiced-arap-emit-enifed-lavirod-snaihtniroc-od-oacalacse\/snaihtniroc\/lobetuf\/setropse\/rb.moc.napmevoj\/\/:sptth'), '_blank')\">Veja a resposta completa em jovempan.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quais os desfalques do Corinthians hoje?<\/h2>\n\n\n<p><\/p>O Tim\u00e3o ter\u00e1 desfalques importantes para a partida: Matheuzinho e Jos\u00e9 Mart\u00ednez est\u00e3o suspensos, enquanto Hugo Souza, Rodrigo Garro e Igor Coronado seguem lesionados.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmth.nacaruh-o-artnoc-oasiced-arap-emit-enifed-lavirod-snaihtniroc-od-oacalacse\/snaihtniroc\/lobetuf\/setropse\/rb.moc.napmevoj\/\/:sptth'), '_blank')\">Veja a resposta completa em jovempan.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem est\u00e1 no banco de reserva do Corinthians hoje?<\/h2>\n\n\n<p><\/p>Escala\u00e7\u00e3o: \u00e0 espera de Dorival, Corinthians ter\u00e1 Orlando Ribeiro no banco e volta de Hugo Souza.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmth.nacaruh-o-artnoc-oasiced-arap-emit-enifed-lavirod-snaihtniroc-od-oacalacse\/snaihtniroc\/lobetuf\/setropse\/rb.moc.napmevoj\/\/:sptth'), '_blank')\">Veja a resposta completa em jovempan.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quais s\u00e3o os desfalques do Corinthians?<\/h2>\n\nS\u00e3o eles: Breno Bidon, Jo\u00e3o Pedro Tchoca, Romero e Andr\u00e9 Ramalho.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('mu-adac-ajev-oimerg-o-artnoc-aditrap-a-arap-sodarudnep-ortauq-e-seuqlafsed-sies-met-snaihtniroc\/619905\/snaihtniroc-od-saiciton\/rb.moc.oamituem.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.meutimao.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quais os desfalques do Corinthians para hoje?<\/h2>\n\n\n<p><\/p>O Tim\u00e3o ter\u00e1 desfalques importantes para a partida: Matheuzinho e Jos\u00e9 Mart\u00ednez est\u00e3o suspensos, enquanto Hugo Souza, Rodrigo Garro e Igor Coronado seguem lesionados.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('mu-adac-ajev-oimerg-o-artnoc-aditrap-a-arap-sodarudnep-ortauq-e-seuqlafsed-sies-met-snaihtniroc\/619905\/snaihtniroc-od-saiciton\/rb.moc.oamituem.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.meutimao.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">O Corinthians tem algum desfalque?<\/h2>\n\n\n<p><\/p>O Tim\u00e3o tem dois desfalques para essa partida: o zagueiro Gustavo Henrique, que faz tratamento de uma h\u00e9rnia inguinal, e Yuri Alberto, que no s\u00e1bado sofreu uma fratura no processo transverso da coluna lombar.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('mu-adac-ajev-oimerg-o-artnoc-aditrap-a-arap-sodarudnep-ortauq-e-seuqlafsed-sies-met-snaihtniroc\/619905\/snaihtniroc-od-saiciton\/rb.moc.oamituem.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.meutimao.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem s\u00e3o os jogadores pendurados do Corinthians?<\/h2>\n\n\n<p><\/p>Os pendurados s\u00e3o: Raniele, Breno Bidon, Yuri Alberto e Memphis.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('mu-adac-ajev-oimerg-o-artnoc-aditrap-a-arap-sodarudnep-ortauq-e-seuqlafsed-sies-met-snaihtniroc\/619905\/snaihtniroc-od-saiciton\/rb.moc.oamituem.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.meutimao.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem est\u00e1 suspenso no Corinthians?<\/h2>\n\n\n<p><\/p>O Tim\u00e3o n\u00e3o vai contar com o zagueiro Cac\u00e1 e o lateral-direito Matheuzinho, ambos por terem levado o terceiro cart\u00e3o amarelo na partida de ida. Al\u00e9m da dupla, o beque F\u00e9lix Torres e o volante Jos\u00e9 Mart\u00ednez tamb\u00e9m n\u00e3o jogar\u00e3o, j\u00e1 que est\u00e3o com as respectivas sele\u00e7\u00f5es, Equador e Venezuela, na Data FIFA.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('mu-adac-ajev-oimerg-o-artnoc-aditrap-a-arap-sodarudnep-ortauq-e-seuqlafsed-sies-met-snaihtniroc\/619905\/snaihtniroc-od-saiciton\/rb.moc.oamituem.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.meutimao.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quando Garro volta?<\/h2>\n\n\n<p><\/p>A estimativa \u00e9 que, por volta do dia 10 de maio, comece esta transi\u00e7\u00e3o com a prepara\u00e7\u00e3o f\u00edsica para que ele retorne no dia 20 de maio&#8221;, disse. Com a data prevista, o argentino deve retornar no dia 21 de maio, contra o Novorizontino, pela Copa do Brasil.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('mu-adac-ajev-oimerg-o-artnoc-aditrap-a-arap-sodarudnep-ortauq-e-seuqlafsed-sies-met-snaihtniroc\/619905\/snaihtniroc-od-saiciton\/rb.moc.oamituem.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.meutimao.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quais s\u00e3o os 11 titulares do Corinthians?<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Hugo Souza Goleiro. ALTURA1,96. IDADE26. &#8230;<\/li>\n<li>M. Donelli Goleiro. ALTURA1,89. &#8230;<\/li>\n<li>Felipe Longo Goleiro. ALTURA1,88. IDADE20. &#8230;<\/li>\n<li>F\u00e9lix Torres Zagueiro. ALTURA1,87. IDADE28. &#8230;<\/li>\n<li>Jo\u00e3o Pedro Zagueiro. ALTURA1,92. IDADE21. &#8230;<\/li>\n<li>Gustavo Henrique Zagueiro. ALTURA1,96. IDADE32. &#8230;<\/li>\n<li>Cac\u00e1 Zagueiro. ALTURA1,87. IDADE26. &#8230;<\/li>\n<li>Andr\u00e9 Ramalho Zagueiro. ALTURA1,82. IDADE33.<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/rb.moc.snaihtniroc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.corinthians.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem s\u00e3o os 11 jogadores do Corinthians?<\/h2>\n\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Felipe Longo goleiro. ALTURA1,88. IDADE20. &#8230;<\/li>\n<li>Hugo Souza goleiro. ALTURA1,96. IDADE26. &#8230;<\/li>\n<li>M. Donelli goleiro. ALTURA1,89. &#8230;<\/li>\n<li>Andr\u00e9 Ramalho zagueiro. ALTURA1,82. IDADE33. &#8230;<\/li>\n<li>Cac\u00e1 zagueiro. ALTURA1,87. IDADE26. &#8230;<\/li>\n<li>F\u00e9lix Torres zagueiro. ALTURA1,87. IDADE28. &#8230;<\/li>\n<li>Gustavo Henrique zagueiro. ALTURA1,96. IDADE32. &#8230;<\/li>\n<li>Jo\u00e3o Pedro zagueiro. ALTURA1,92. IDADE21.<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/rb.moc.snaihtniroc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.corinthians.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 o nome do 11o Corinthians?<\/h2>\n\n\n<p><\/p><p>Nome | POS<\/p><table border=\"1\"><tr><td>Igor Coronado77<\/td><td>M<\/td><\/tr><tr><td>Yuri Alberto9<\/td><td>A<\/td><\/tr><tr><td>Memphis Depay10<\/td><td>A<\/td><\/tr><tr><td>\u00c1ngel Romero11<\/td><td>A<\/td><\/tr><\/table><br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/rb.moc.snaihtniroc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.corinthians.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 o elenco atual do Corinthians?<\/h2>\n\n\n<p><\/p><p>Elenco atual do Sport Club Corinthians Paulista<\/p><table border=\"1\"><tr><td>6<\/td><td>LE<\/td><td>Diego Palacios<\/td><\/tr><tr><td>7<\/td><td>V<\/td><td>Maycon \u00b2<\/td><\/tr><tr><td>8<\/td><td>M<\/td><td>Rodrigo Garro<\/td><\/tr><tr><td>9<\/td><td>A<\/td><td>Yuri Alberto<\/td><\/tr><\/table><br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/rb.moc.snaihtniroc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.corinthians.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quais s\u00e3o os 5 melhores jogadores do Corinthians?<\/h2>\n\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>1\u00ba Cl\u00e1udio Christ\u00f3vam. Gols: 306. Jogos: 551. Gols por jogo: 0.56. &#8230;<\/li>\n<li>2\u00ba Baltazar. Gols: 269. Jogos: 405. Gols por jogo: 0.66. &#8230;<\/li>\n<li>3\u00ba Teleco. Gols: 257. Jogos: 250. &#8230;<\/li>\n<li>4\u00ba Neco. Gols: 242. Jogos: 297. &#8230;<\/li>\n<li>5\u00ba Marcelinho Carioca. Gols: 206. Jogos: 433. &#8230;<\/li>\n<li>6\u00ba Serv\u00edlio. Gols: 200. Jogos: 364. &#8230;<\/li>\n<li>7\u00ba Luizinho. Gols: 175. Jogos: 608. &#8230;<\/li>\n<li>8\u00ba S\u00f3crates. Gols: 172. Jogos: 298.<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/rb.moc.snaihtniroc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.corinthians.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Felipe Longo \u00e9 goleiro do Corinthians?<\/h2>\n\n\n<p><\/p>Felipe Longo Fernandes da Silva, conhecido apenas como Felipe Longo, \u00e9 um goleiro do Corinthians. Ele nasceu na cidade de S\u00e3o Paulo no dia 5 de mar\u00e7o de 2005. O defensor come\u00e7ou no futsal do Corinthians aos oito anos e depois fez a transi\u00e7\u00e3o para o campo.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/rb.moc.snaihtniroc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.corinthians.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quanto saiu o jogo Corinthians-C Crici\u00fama?<\/h2>\n\nO Corinthians conquistou uma vit\u00f3ria heroica neste s\u00e1bado. O time saiu atr\u00e1s, mas reagiu e buscou a virada contra o Crici\u00fama no Heriberto Hulse, vencendo por 4 a 2 e alcan\u00e7ando sua s\u00e9tima vit\u00f3ria seguida no Campeonato Brasileiro.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.snaihtniroc-4-x-2-amuicirc-ed-sotnemom-serohlem-soa-atsissa\/03\/11\/4202\/aiciton\/a-eires-oarielisarb\/lobetuf\/cs\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quanto saiu o jogo Corinthians e Crici\u00fama?<\/h2>\n\n\n<p><\/p>O Corinthians conquistou uma vit\u00f3ria heroica neste s\u00e1bado. O time saiu atr\u00e1s, mas reagiu e buscou a virada contra o Crici\u00fama no Heriberto Hulse, vencendo por 4 a 2 e alcan\u00e7ando sua s\u00e9tima vit\u00f3ria seguida no Campeonato Brasileiro.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.snaihtniroc-4-x-2-amuicirc-ed-sotnemom-serohlem-soa-atsissa\/03\/11\/4202\/aiciton\/a-eires-oarielisarb\/lobetuf\/cs\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quantos pontos o Corinthians precisa para n\u00e3o ser rebaixado?<\/h2>\n\n\n<p><\/p>Ou seja, em uma conta simples o Corinthians precisa vencer tr\u00eas dos sete jogos restantes para garantir a perman\u00eancia na S\u00e9rie A. Ou duas vit\u00f3rias e dois empates. Na temporada passada, tamb\u00e9m em disputa contra a queda, o Corinthians conseguiu se garantir na S\u00e9rie A apenas nas rodadas finais.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.snaihtniroc-4-x-2-amuicirc-ed-sotnemom-serohlem-soa-atsissa\/03\/11\/4202\/aiciton\/a-eires-oarielisarb\/lobetuf\/cs\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Como terminou o jogo do Corinthians hoje?<\/h2>\n\n\n<p><\/p>Acabou Corinthians e Gr\u00eamio empatam em 1 a 1 na Arena do Gr\u00eamio. O gol alvinegro foi marcado por Breno Bidon.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.snaihtniroc-4-x-2-amuicirc-ed-sotnemom-serohlem-soa-atsissa\/03\/11\/4202\/aiciton\/a-eires-oarielisarb\/lobetuf\/cs\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem classificou na Sul-Americana Corinthians ou Racing?<\/h2>\n\n\n<p><\/p>Nesta quinta-feira (15), o Corinthians venceu o Racing por 1 a 0, no Uruguai, e entrou na zona de classifica\u00e7\u00e3o para o mata-mata da Copa Sul-Americana. Em partida realizada no Est\u00e1dio Centen\u00e1rio, o \u00fanico gol da vit\u00f3ria foi marcado por Matheus Bidu, aos 29 minutos da segunda etapa.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.snaihtniroc-4-x-2-amuicirc-ed-sotnemom-serohlem-soa-atsissa\/03\/11\/4202\/aiciton\/a-eires-oarielisarb\/lobetuf\/cs\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem ganhou o jogo de hoje?<\/h2>\n\n\n<p><\/p>Atl\u00e9tico-GO 1 x 2 S\u00e3o Paulo | Campeonato Brasileiro: melhores momentos.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.snaihtniroc-4-x-2-amuicirc-ed-sotnemom-serohlem-soa-atsissa\/03\/11\/4202\/aiciton\/a-eires-oarielisarb\/lobetuf\/cs\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem fez os 4 gols do Corinthians?<\/h2>\n\n\n<p><\/p>Yuri Alberto e Igor Coronado marcaram os gols da rodada! A partida ainda teve dois gols anulados pelo VAR. #brasileir\u00e3o2025 #melhoresmomentos #corinthians &#8212; Fiel, n\u00e3o caia em golpes!<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.snaihtniroc-4-x-2-amuicirc-ed-sotnemom-serohlem-soa-atsissa\/03\/11\/4202\/aiciton\/a-eires-oarielisarb\/lobetuf\/cs\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quanto o Corinthians j\u00e1 arrecadou na vaquinha?<\/h2>\n\nCampanha arrecadou R$ 40 milh\u00f5es desde novembro, longe do objetivo de R$ 700 milh\u00f5es para quitar financiamento. A campanha de arrecada\u00e7\u00e3o liderada pelos Gavi\u00f5es da Fiel para quitar o financiamento da Neo Qu\u00edmica Arena completou 5 meses e alcan\u00e7ou R$ 40 milh\u00f5es, o equivalente a 5,7% da meta total.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.aditab-atem-ad-tnecrep45-moc-edatem-a-agehc-snaihtniroc-od-anera-a-ragap-arap-ahnapmac\/82\/20\/5202\/aiciton\/snaihtniroc\/semit\/lobetuf\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quanto o Corinthians j\u00e1 arrecadou em 2025?<\/h2>\n\n\n<p><\/p>O Corinthians registrou um super\u00e1vit de R$ 12,1 milh\u00f5es no primeiro bimestre de 2025. Neste per\u00edodo, a maior arrecada\u00e7\u00e3o do clube foi com direitos de transmiss\u00e3o, no valor de R$ 78,8 milh\u00f5es.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.aditab-atem-ad-tnecrep45-moc-edatem-a-agehc-snaihtniroc-od-anera-a-ragap-arap-ahnapmac\/82\/20\/5202\/aiciton\/snaihtniroc\/semit\/lobetuf\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual o valor arrecadado na vaquinha do Corinthians?<\/h2>\n\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>Campanha arrecadou cerca de R$ 34,6 milh\u00f5es at\u00e9 aqui<\/li>\n<li> A vaquinha do Corinthians para pagar a d\u00edvida da Neo Qu\u00edmica Arena segue ativa, entenda como as novas medidas podem afetar as arrecada\u00e7\u00f5es. A realiza\u00e7\u00e3o de uma doa\u00e7\u00e3o acima de 5 mil reais no Pix por uma pessoa f\u00edsica n\u00e3o ser\u00e1 taxada.<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.aditab-atem-ad-tnecrep45-moc-edatem-a-agehc-snaihtniroc-od-anera-a-ragap-arap-ahnapmac\/82\/20\/5202\/aiciton\/snaihtniroc\/semit\/lobetuf\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual foi a arrecada\u00e7\u00e3o anual do Corinthians em 2024?<\/h2>\n\n\n<p><\/p>O Sport Club Corinthians Paulista atingiu receita bruta recorde de R$ 1,11 bilh\u00e3o em 2024. Trata-se de um crescimento de 18,9% ante 2023. Em contrapartida, a d\u00edvida tamb\u00e9m avan\u00e7ou no per\u00edodo, de R$ 2,16 bilh\u00f5es para R$ 2,57 bilh\u00f5es. A alta registrada foi de 18,8%.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.aditab-atem-ad-tnecrep45-moc-edatem-a-agehc-snaihtniroc-od-anera-a-ragap-arap-ahnapmac\/82\/20\/5202\/aiciton\/snaihtniroc\/semit\/lobetuf\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quanto a campanha Doe Arena j\u00e1 arrecadou?<\/h2>\n\n\n<p><\/p>\ud83c\udff3 A Campanha Doe Arena atingiu a marca de R$ 38 milh\u00f5es arrecadados, um feito que demonstra o engajamento e a paix\u00e3o da torcida corinthiana. Essa j\u00e1 \u00e9 uma das maiores campanhas de doa\u00e7\u00e3o realizadas no Brasil, mas o nosso grande objetivo ainda n\u00e3o foi alcan\u00e7ado.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.aditab-atem-ad-tnecrep45-moc-edatem-a-agehc-snaihtniroc-od-anera-a-ragap-arap-ahnapmac\/82\/20\/5202\/aiciton\/snaihtniroc\/semit\/lobetuf\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual o valor atual da vaquinha da Arena Corinthians?<\/h2>\n\n\n<p><\/p>A vaquinha iniciou \u00e0s 19h10, em refer\u00eancia ao ano de funda\u00e7\u00e3o do clube (1910), e teve forte ades\u00e3o nos primeiros dias: 28. nov. 2024 com R$ 7,46 milh\u00f5es ; 29.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.aditab-atem-ad-tnecrep45-moc-edatem-a-agehc-snaihtniroc-od-anera-a-ragap-arap-ahnapmac\/82\/20\/5202\/aiciton\/snaihtniroc\/semit\/lobetuf\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Como est\u00e1 a arrecada\u00e7\u00e3o da vaquinha da Arena Corinthians?<\/h2>\n\n\n<p><\/p>A campanha de arrecada\u00e7\u00e3o para quitar a d\u00edvida da Neo Qu\u00edmica Arena alcan\u00e7ou R$ 38 milh\u00f5es ap\u00f3s 3 meses, o que representa 5,43% da meta de R$ 700 milh\u00f5es. A iniciativa foi lan\u00e7ada pela Gavi\u00f5es da Fiel, principal torcida organizada do Corinthians, em 27 de novembro de 2024, \u00e0s 19h30.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.aditab-atem-ad-tnecrep45-moc-edatem-a-agehc-snaihtniroc-od-anera-a-ragap-arap-ahnapmac\/82\/20\/5202\/aiciton\/snaihtniroc\/semit\/lobetuf\/moc.obolg.eg\/\/:sptth'), '_blank')\">Veja a resposta completa em ge.globo.com<\/span><\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Time prov\u00e1vel: Gustavo; Dudu, Rodrigo, Tobias Figueiredo e Marcelo Hermes; Barreto, Newton, Ronald e Matheusinho (Fellipe Mateus); Bolasie e Felipe Vizeu (Pedro Rocha). Quem est\u00e1 fora: Ningu\u00e9m. Pendurados: Alisson, Fellipe Mateus, Gustavo, Jonathan, Newton e Tobias Figueiredo. Qual foi a escala\u00e7\u00e3o do Corinthians contra o Crici\u00fama? Para encarar o Crici\u00fama o Corinthians contar\u00e1 com o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[43],"tags":[],"class_list":["post-3275","post","type-post","status-publish","format-standard","hentry","category-perguntas-frequentes"],"_links":{"self":[{"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts\/3275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/comments?post=3275"}],"version-history":[{"count":1,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts\/3275\/revisions"}],"predecessor-version":[{"id":3276,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts\/3275\/revisions\/3276"}],"wp:attachment":[{"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/media?parent=3275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/categories?post=3275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/tags?post=3275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}