{"id":3273,"date":"2025-06-25T08:06:15","date_gmt":"2025-06-25T08:06:15","guid":{"rendered":"http:\/\/3710e1ac-b026-407d-acc7-93aad4efb379"},"modified":"2025-06-25T08:06:15","modified_gmt":"2025-06-25T08:06:15","slug":"escalacao-do-palmeiras-contra-o-internacional","status":"publish","type":"post","link":"https:\/\/tsports.app.br\/perguntas-frequentes\/escalacao-do-palmeiras-contra-o-internacional\/","title":{"rendered":"Escala\u00e7\u00e3o do palmeiras contra o internacional"},"content":{"rendered":"PALMEIRAS: Weverton; Marcos Rocha, Murilo, Gustavo G\u00f3mez e Piquerez; Richard R\u00edos, Lucas Evangelista e Raphael Veiga; Est\u00eav\u00e3o, Facundo Torres e Flaco L\u00f3pez.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/serpn-oacalacse-e-oiraroh-oviv-oa-ritsissa-edno-sebulc-ed-laidnum-on-sariemlap-x-imaim-retni\/lobetuf\/setropse\/rb.moc.oadatse.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.estadao.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual a escala\u00e7\u00e3o do Palmeiras para o jogo de hoje contra o Internacional?<\/h2>\n\nPALMEIRAS : Weverton; Marcos Rocha, G\u00f3mez, Murilo e Piquerez; Lucas Evangelista, Richard R\u00edos e Raphael Veiga; Est\u00eav\u00e3o, Flaco L\u00f3pez e Facundo Torres.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/laidnum-od-ogoj-oa-ritsissa-edno-e-seocalacse-imaim-retni-x-sariemlap\/lanoicanretni-lobetuf\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual a escala\u00e7\u00e3o do Palmeiras contra o Inter?<\/h2>\n\n\n<p><\/p>PALMEIRAS: Weverton; Marcos Rocha, G\u00f3mez, Murilo e Piquerez; Lucas Evangelista, Richard R\u00edos e Raphael Veiga; Est\u00eav\u00e3o, Flaco L\u00f3pez e Facundo Torres.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/laidnum-od-ogoj-oa-ritsissa-edno-e-seocalacse-imaim-retni-x-sariemlap\/lanoicanretni-lobetuf\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual \u00e9 a escala\u00e7\u00e3o do Palmeiras para o jogo de hoje?<\/h2>\n\n\n<p><\/p>A prov\u00e1vel escala\u00e7\u00e3o do Palmeiras \u00e9: Weverton; Giay, Gustavo G\u00f3mez e Murilo; Felipe Anderson, An\u00edbal Moreno, Richard R\u00edos e Piquerez; Est\u00eav\u00e3o, Vitor Roque e Maur\u00edcio.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/laidnum-od-ogoj-oa-ritsissa-edno-e-seocalacse-imaim-retni-x-sariemlap\/lanoicanretni-lobetuf\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quando \u00e9 o jogo do Palmeiras com o Inter Miami?<\/h2>\n\n\n<p><\/p>O Palmeiras entra em campo diante do Inter Miami-EUA, nesta segunda-feira (23), \u00e0s 22h (de Bras\u00edlia), no Hard Rock Stadium, em Miami, pela \u00faltima rodada da fase de grupos do Mundial de Clubes da Fifa.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/laidnum-od-ogoj-oa-ritsissa-edno-e-seocalacse-imaim-retni-x-sariemlap\/lanoicanretni-lobetuf\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem classificou Palmeiras ou Inter de Miami?<\/h2>\n\n\n<p><\/p>O t\u00e9cnico do Inter Miami, Javier Mascherano, teve sentimentos mistos no empate por 2 a 2 com o Palmeiras, nesta segunda-feira, que classificou o time \u00e0s oitavas de final da Copa do Mundo de Clubes.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/laidnum-od-ogoj-oa-ritsissa-edno-e-seocalacse-imaim-retni-x-sariemlap\/lanoicanretni-lobetuf\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Como est\u00e1 a chave do Palmeiras no Mundial?<\/h2>\n\nNas oitavas, o Verd\u00e3o agora far\u00e1 cl\u00e1ssico brasileiro contra o Botafogo, enquanto o Inter enfrenta o poderoso PSG, atual campe\u00e3o da Champions League.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.sevahc-e-sodinifed-aj-sotnorfnoc-ajev-ogofatob-e-sariemlap-moc-laidnum-od-savatio\/42\/60\/5202\/aiciton\/sebulc-ed-laidnum\/setropse\/moc.obolg.obolgo\/\/:sptth'), '_blank')\">Veja a resposta completa em oglobo.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Como ficou a situa\u00e7\u00e3o do Palmeiras no Mundial?<\/h2>\n\n\n<p><\/p>A classifica\u00e7\u00e3o para as oitavas de final garantiu ao Verd\u00e3o faturar 4 milh\u00f5es de d\u00f3lares (R$ 22,4 milh\u00f5es) em premia\u00e7\u00f5es. O Palmeiras tamb\u00e9m recebeu R$ 16,21 milh\u00f5es de d\u00f3lares (R$ 90 milh\u00f5es) pela participa\u00e7\u00e3o no Mundial de Clubes.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.sevahc-e-sodinifed-aj-sotnorfnoc-ajev-ogofatob-e-sariemlap-moc-laidnum-od-savatio\/42\/60\/5202\/aiciton\/sebulc-ed-laidnum\/setropse\/moc.obolg.obolgo\/\/:sptth'), '_blank')\">Veja a resposta completa em oglobo.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem o Palmeiras pode pegar nas quartas do Mundial?<\/h2>\n\n\n<p><\/p>Dessa forma, Palmeiras ou Botafogo vai enfrentar Bayern de Munique ou Benfica ou Chelsea ou Esp\u00e9rance.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.sevahc-e-sodinifed-aj-sotnorfnoc-ajev-ogofatob-e-sariemlap-moc-laidnum-od-savatio\/42\/60\/5202\/aiciton\/sebulc-ed-laidnum\/setropse\/moc.obolg.obolgo\/\/:sptth'), '_blank')\">Veja a resposta completa em oglobo.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Como ficou o grupo do Palmeiras no Mundial de Clubes?<\/h2>\n\n\n<p><\/p>Palmeiras, Inter Miami, Porto e Al Ahly definiram os dois primeiros colocados do grupo A da Copa do Mundo de Clubes da Fifa. Palmeiras empatou por 2 a 2 com o Inter Miami e se classificou na primeira posi\u00e7\u00e3o, enquanto o time norte-americano passa em segundo.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.sevahc-e-sodinifed-aj-sotnorfnoc-ajev-ogofatob-e-sariemlap-moc-laidnum-od-savatio\/42\/60\/5202\/aiciton\/sebulc-ed-laidnum\/setropse\/moc.obolg.obolgo\/\/:sptth'), '_blank')\">Veja a resposta completa em oglobo.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Como est\u00e1 a classifica\u00e7\u00e3o da chave do Palmeiras?<\/h2>\n\n\n<p><\/p><p>Classifica\u00e7\u00e3o<\/p><table border=\"1\"><tr><td>4<\/td><td>PalmeirasPAL<\/td><td>0<\/td><\/tr><tr><td>5<\/td><td>BahiaBAH<\/td><td>2<\/td><\/tr><tr><td>6<\/td><td>FluminenseFLU<\/td><td>1<\/td><\/tr><tr><td>7<\/td><td>MGCAM<\/td><td>2<\/td><\/tr><\/table><br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.sevahc-e-sodinifed-aj-sotnorfnoc-ajev-ogofatob-e-sariemlap-moc-laidnum-od-savatio\/42\/60\/5202\/aiciton\/sebulc-ed-laidnum\/setropse\/moc.obolg.obolgo\/\/:sptth'), '_blank')\">Veja a resposta completa em oglobo.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual a chave do Palmeiras no Mundial?<\/h2>\n\n\n<p><\/p>Veja o que j\u00e1 est\u00e1 definido nas chaves das as oitavas do Mundial: Chave da esquerda (os vencedores de cada dupla de jogos se enfrentam nas quartas): Palmeiras x Botafogo.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.sevahc-e-sodinifed-aj-sotnorfnoc-ajev-ogofatob-e-sariemlap-moc-laidnum-od-savatio\/42\/60\/5202\/aiciton\/sebulc-ed-laidnum\/setropse\/moc.obolg.obolgo\/\/:sptth'), '_blank')\">Veja a resposta completa em oglobo.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">O que o Palmeiras precisa para se classificar no Mundial?<\/h2>\n\n\n<p><\/p>O Palmeiras assegura a classifica\u00e7\u00e3o e a primeira coloca\u00e7\u00e3o do grupo A se vencer ou, ao menos, empatar contra o Inter Miami.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('lmthg.sevahc-e-sodinifed-aj-sotnorfnoc-ajev-ogofatob-e-sariemlap-moc-laidnum-od-savatio\/42\/60\/5202\/aiciton\/sebulc-ed-laidnum\/setropse\/moc.obolg.obolgo\/\/:sptth'), '_blank')\">Veja a resposta completa em oglobo.globo.com<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem ganha, Palmeiras ou Al Ahly?<\/h2>\n\nO Palmeiras venceu o Al Ahly por 2 a 0 nesta quinta-feira (19), no MetLife Stadium, em Nova Jersey, pela segunda rodada da Copa do Mundo de Clubes da Fifa.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/sebulc-ed-laidnum-on-esaf-ed-racnava-arap-asicerp-sariemlap-o-euq-od-abias\/sariemlap\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem ganha, Palmeiras ou Al Ahli?<\/h2>\n\n\n<p><\/p>Palmeiras vai vencendo o time eg\u00edpcio por 2 a 0, em duelo v\u00e1lido pelo grupo A da Copa do Mundo. O duelo entre Palmeiras e Al Ahly foi interrompido aos 17 minutos do segundo tempo por conta do mau tempo em Nova Jersey.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/sebulc-ed-laidnum-on-esaf-ed-racnava-arap-asicerp-sariemlap-o-euq-od-abias\/sariemlap\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual o placar de Palmeiras e Hilal?<\/h2>\n\n\n<p><\/p>Ap\u00f3s um empate por 0 a 0, o time eg\u00edpcio venceu por 3 a 2 nos p\u00eanaltis na disputa pelo terceiro lugar da Copa Intercontinental da FIFA\u2122, em fevereiro de 2021.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/sebulc-ed-laidnum-on-esaf-ed-racnava-arap-asicerp-sariemlap-o-euq-od-abias\/sariemlap\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem vai ganhar, Palmeiras ou Inter Miami?<\/h2>\n\n\n<p><\/p>O Palmeiras levou um susto e tanto, mas arrancou empate em 2 a 2 com o Inter Miami, nesta segunda-feira (23), e avan\u00e7ou \u00e0s oitavas de final da Copa do Mundo de Clubes como l\u00edder do grupo A.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/sebulc-ed-laidnum-on-esaf-ed-racnava-arap-asicerp-sariemlap-o-euq-od-abias\/sariemlap\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual time brasileiro perdeu para Al Ahly?<\/h2>\n\n\n<p><\/p>Derrotado pelo Tigres, do M\u00e9xico, por 1 a 0 na semifinal, o Palmeiras perdeu por 3 a 2 nos p\u00eanaltis a disputa com o Al Ahly pelo terceiro lugar.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/sebulc-ed-laidnum-on-esaf-ed-racnava-arap-asicerp-sariemlap-o-euq-od-abias\/sariemlap\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quantas vezes o Palmeiras enfrentou o Al Ahly?<\/h2>\n\n\n<p><\/p>O Palmeiras nunca perdeu para o Al Ahly. Os dois clubes j\u00e1 se enfrentaram duas vezes, ambas pelo Mundial de Clubes &#8211; agora Copa Intercontinental.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/sebulc-ed-laidnum-on-esaf-ed-racnava-arap-asicerp-sariemlap-o-euq-od-abias\/sariemlap\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Como \u00e9 que ficou o jogo do Palmeiras no Mundial?<\/h2>\n\n\n<p><\/p>Mundial: Palmeiras empata com Miami e pegar\u00e1 Botafogo nas oitavas &#8211; ESPN.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/sebulc-ed-laidnum-on-esaf-ed-racnava-arap-asicerp-sariemlap-o-euq-od-abias\/sariemlap\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quanto ficaram o Palmeiras e o Inter Miami?<\/h2>\n\nO t\u00e9cnico do Inter Miami, Javier Mascherano, teve sentimentos mistos no empate por 2 a 2 com o Palmeiras, nesta segunda-feira, que classificou o time \u00e0s oitavas de final da Copa do Mundo de Clubes.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/laidnum-on-orielisarb-oleud-araf-e-imaim-retni-moc-etapme-acnarra-sariemlap\/lanoicanretni-lobetuf\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quanto ficou o jogo do Palmeiras contra o time do Messi?<\/h2>\n\n\n<p><\/p>O Palmeiras sofreu muito com a dupla Messi e Luis Su\u00e1rez e chegou a estar perdendo por 2 a 0, mas buscou o empate por 2 a 2 com o Inter Miami, nesta segunda-feira (23), no Hard Rock Stadium, em duelo v\u00e1lido pela 3\u00aa rodada do grupo A do Mundial de Clubes.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/laidnum-on-orielisarb-oleud-araf-e-imaim-retni-moc-etapme-acnarra-sariemlap\/lanoicanretni-lobetuf\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quanto vale o Inter de Miami hoje?<\/h2>\n\n\n<p><\/p>Ap\u00f3s a chegada de Messi, o clube conquistou seu primeiro t\u00edtulo da hist\u00f3ria. Em 2024, o valor estimado da equipe pela Forbes \u00e9 de 1,03 bilh\u00e3o de d\u00f3lares, ficando em segundo lugar na liga, atr\u00e1s do Los Angeles Football Club.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/laidnum-on-orielisarb-oleud-araf-e-imaim-retni-moc-etapme-acnarra-sariemlap\/lanoicanretni-lobetuf\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem \u00e9 maior, Inter ou Palmeiras?<\/h2>\n\n\n<p><\/p><p># | Clube | Total<\/p><table border=\"1\"><tr><td>3\u00b0<\/td><td>Internacional<\/td><td>7<\/td><\/tr><tr><\/tr><\/table><p>Flamengo<\/p><table border=\"1\"><\/tr><tr><td>6\u00b0<\/td><td>Gr\u00eamio<\/td><td>6<\/td><\/tr><tr><\/tr><\/table><p>Palmeiras<\/p><table border=\"1\"><\/tr><\/table><br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/laidnum-on-orielisarb-oleud-araf-e-imaim-retni-moc-etapme-acnarra-sariemlap\/lanoicanretni-lobetuf\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Quem fez o gol do Inter Miami hoje?<\/h2>\n\n\n<p><\/p>Aos 18 min do 2\u00ba tempo &#8211; Gol do Inter Miami! Luis Suarez passa pela zaga e faz um gola\u00e7o.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/laidnum-on-orielisarb-oleud-araf-e-imaim-retni-moc-etapme-acnarra-sariemlap\/lanoicanretni-lobetuf\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual foi o placar de Palmeiras e Miami?<\/h2>\n\n\n<p><\/p>Inter Miami 2 x 2 Palmeiras | Melhores Momentos | Copa do Mundo de Clubes.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/laidnum-on-orielisarb-oleud-araf-e-imaim-retni-moc-etapme-acnarra-sariemlap\/lanoicanretni-lobetuf\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">\u00c9 verdade que o Palmeiras vai enfrentar o time do Messi?<\/h2>\n\n\n<p><\/p>Valendo uma vaga nas oitavas de final da Copa do Mundo de Clubes, o Palmeiras enfrentar\u00e1 nesta segunda-feira Lionel Messi, camisa 10 do Inter Miami e um dos maiores jogadores da hist\u00f3ria do futebol mundial.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/laidnum-on-orielisarb-oleud-araf-e-imaim-retni-moc-etapme-acnarra-sariemlap\/lanoicanretni-lobetuf\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Onde assistir o jogo do Palmeiras hoje?<\/h2>\n\nO jogo ser\u00e1 \u00e0s 22h (de Bras\u00edlia), no Hard Rock Stadium, em Miami, e ter\u00e1 transmiss\u00e3o de TV Globo, SporTV, Caz\u00e9TV (YouTube), Globoplay e DAZN (plataformas de streaming).<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/laidnum-od-ogoj-oa-ritsissa-edno-e-seocalacse-imaim-retni-x-sariemlap\/lanoicanretni-lobetuf\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Onde ser\u00e1 transmitido o jogo do Palmeiras hoje?<\/h2>\n\n\n<p><\/p>A partida ser\u00e1 transmitida em TV aberta (TV Globo), TV fechada (Sportv) e no streaming (Caz\u00e9TV e DAZN).<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/laidnum-od-ogoj-oa-ritsissa-edno-e-seocalacse-imaim-retni-x-sariemlap\/lanoicanretni-lobetuf\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Onde vai passar o jogo hoje?<\/h2>\n\n\n<p><\/p>\n\n<ul class=\"wp-block-list\">\n<li>16h &#8211; Benfica x Bayern de Munique &#8211; DAZN, Globo, Sportv e Caz\u00e9TV.<\/li>\n<li>16h &#8211; Auckland City x Boca Juniors &#8211; DAZN, Sportv 2 e Caz\u00e9TV.<\/li>\n<li>22h &#8211; Los Angeles FC x Flamengo &#8211; DAZN, Globo, Sportv e Caz\u00e9TV.<\/li>\n<li>22h &#8211; Esp\u00e9rance x Chelsea &#8211; DAZN, Sportv 2 e Caz\u00e9TV.<\/li>\n<\/ul>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/laidnum-od-ogoj-oa-ritsissa-edno-e-seocalacse-imaim-retni-x-sariemlap\/lanoicanretni-lobetuf\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Vai ter jogo do Palmeiras hoje na Globo?<\/h2>\n\n\n<p><\/p>Palmeiras x Atl\u00e9tico-MG: hoje, 21h30, ao vivo na Globo.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/laidnum-od-ogoj-oa-ritsissa-edno-e-seocalacse-imaim-retni-x-sariemlap\/lanoicanretni-lobetuf\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Onde vai passar Mirassol e Palmeiras hoje?<\/h2>\n\n\n<p><\/p>A partida ser\u00e1 no Mai\u00e3o, em Mirassol, e ter\u00e1 transmiss\u00e3o do Uol Play, do Nosso Futebol e da Zapping TV, al\u00e9m de tempo real do CNN Esportes.<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/laidnum-od-ogoj-oa-ritsissa-edno-e-seocalacse-imaim-retni-x-sariemlap\/lanoicanretni-lobetuf\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Que canal vai passar o jogo do Palmeiras e Inter Miami?<\/h2>\n\n\n<p><\/p>O jogo ser\u00e1 \u00e0s 22h (de Bras\u00edlia), no Hard Rock Stadium, em Miami, e ter\u00e1 transmiss\u00e3o de TV Globo, SporTV, Caz\u00e9TV (YouTube), Globoplay e DAZN (plataformas de streaming).<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/laidnum-od-ogoj-oa-ritsissa-edno-e-seocalacse-imaim-retni-x-sariemlap\/lanoicanretni-lobetuf\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Qual canal vai transmitir Sporting Cristal Palmeiras?<\/h2>\n\n\n<p><\/p>Transmiss\u00e3o: TV Globo (para S\u00e3o Paulo e Paran\u00e1).<br \/>\n<div class='article-actions'><span class='report-it'><span class='a' onclick=\"window.open('https:\/\/tsports.app.br\/perguntas-frequentes\/solicitar-remocao', '_blank')\">Solicita\u00e7\u00e3o de remo\u00e7\u00e3o<\/span><\/span><span class='spacer'>|<\/span><span class='view-url' onclick=\"window.open(reverse('\/laidnum-od-ogoj-oa-ritsissa-edno-e-seocalacse-imaim-retni-x-sariemlap\/lanoicanretni-lobetuf\/lobetuf\/setropse\/rb.moc.lisarbnnc.www\/\/:sptth'), '_blank')\">Veja a resposta completa em www.cnnbrasil.com.br<\/span><\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>PALMEIRAS: Weverton; Marcos Rocha, Murilo, Gustavo G\u00f3mez e Piquerez; Richard R\u00edos, Lucas Evangelista e Raphael Veiga; Est\u00eav\u00e3o, Facundo Torres e Flaco L\u00f3pez. Qual a escala\u00e7\u00e3o do Palmeiras para o jogo de hoje contra o Internacional? PALMEIRAS : Weverton; Marcos Rocha, G\u00f3mez, Murilo e Piquerez; Lucas Evangelista, Richard R\u00edos e Raphael Veiga; Est\u00eav\u00e3o, Flaco L\u00f3pez e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[43],"tags":[],"class_list":["post-3273","post","type-post","status-publish","format-standard","hentry","category-perguntas-frequentes"],"_links":{"self":[{"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts\/3273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/comments?post=3273"}],"version-history":[{"count":1,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts\/3273\/revisions"}],"predecessor-version":[{"id":3274,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/posts\/3273\/revisions\/3274"}],"wp:attachment":[{"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/media?parent=3273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/categories?post=3273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tsports.app.br\/perguntas-frequentes\/wp-json\/wp\/v2\/tags?post=3273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}